{"id":77,"date":"2024-09-02T18:18:16","date_gmt":"2024-09-02T16:18:16","guid":{"rendered":"https:\/\/www.proroofsrl.com\/?page_id=77"},"modified":"2025-02-09T18:04:54","modified_gmt":"2025-02-09T17:04:54","slug":"sistemas-de-fijacion-estancos","status":"publish","type":"page","link":"https:\/\/www.proroofsrl.com\/es\/sistemi-di-fissaggio-a-tenuta-stagna\/","title":{"rendered":"Sistemas de fijaci\u00f3n estancos"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"77\" class=\"elementor elementor-77\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-undefined-946b46b e-flex e-con-boxed e-con e-parent\" data-id=\"undefined-946b46b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;opacity-tilt&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 2600 131.1\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L2600 0 2600 69.1 0 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.5\" d=\"M0 0L2600 0 2600 69.1 0 69.1z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.25\" d=\"M2600 0L0 0 0 130.1 2600 69.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-undefined-2ab98cf e-con-full e-flex e-con e-child\" data-id=\"undefined-2ab98cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-undefined-7347973 elementor-widget elementor-widget-heading\" data-id=\"undefined-7347973\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sistemas de fijaci\u00f3n estancos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0091b69 e-con-full e-flex e-con e-child\" data-id=\"0091b69\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9da6010 elementor-widget elementor-widget-text-editor\" data-id=\"9da6010\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-ccp-border-bottom=\"0px none #000000\" data-ccp-padding-bottom=\"0px\" data-ccp-border-between=\"0px none #000000\" data-ccp-padding-between=\"0px\"><span data-contrast=\"none\">La instalaci\u00f3n de superestructuras como, por ejemplo, paneles fotovoltaicos, t\u00e9rmicos solares, tuber\u00edas, cables de calefacci\u00f3n, antenas parab\u00f3licas, etc., siempre ha suscitado inquietudes y planteado limitaciones particulares tanto al dise\u00f1ador como al aplicador.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:480,&quot;335572071&quot;:0,&quot;335572072&quot;:0,&quot;335572073&quot;:4278190080,&quot;335572075&quot;:0,&quot;335572076&quot;:0,&quot;335572077&quot;:4278190080,&quot;335572079&quot;:0,&quot;335572080&quot;:0,&quot;335572081&quot;:4278190080,&quot;335572083&quot;:0,&quot;335572084&quot;:0,&quot;335572085&quot;:4278190080,&quot;335572087&quot;:0,&quot;335572088&quot;:0,&quot;335572089&quot;:4278190080,&quot;469789798&quot;:&quot;none&quot;,&quot;469789802&quot;:&quot;none&quot;,&quot;469789806&quot;:&quot;none&quot;,&quot;469789810&quot;:&quot;none&quot;,&quot;469789814&quot;:&quot;none&quot;}\">\u00a0<\/span><\/p><p data-ccp-border-bottom=\"0px none #000000\" data-ccp-padding-bottom=\"0px\" data-ccp-border-between=\"0px none #000000\" data-ccp-padding-between=\"0px\"><span data-contrast=\"none\">La experiencia acumulada durante m\u00e1s de 30 a\u00f1os en el sector de la impermeabilizaci\u00f3n ha permitido desarrollar una serie de productos, identificados bajo la marca <\/span><span data-contrast=\"none\">FastEnerGrip<\/span><span data-contrast=\"none\">, <\/span><span data-contrast=\"none\">i<\/span><span data-contrast=\"none\">n capaz de garantizar al mismo tiempo una<\/span><span data-contrast=\"none\">na alta resistencia <\/span><span data-contrast=\"none\">mec\u00e1nica<\/span> <span data-contrast=\"none\">y una estanqueidad total y perfecta.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:480,&quot;335572071&quot;:0,&quot;335572072&quot;:0,&quot;335572073&quot;:4278190080,&quot;335572075&quot;:0,&quot;335572076&quot;:0,&quot;335572077&quot;:4278190080,&quot;335572079&quot;:0,&quot;335572080&quot;:0,&quot;335572081&quot;:4278190080,&quot;335572083&quot;:0,&quot;335572084&quot;:0,&quot;335572085&quot;:4278190080,&quot;335572087&quot;:0,&quot;335572088&quot;:0,&quot;335572089&quot;:4278190080,&quot;469789798&quot;:&quot;none&quot;,&quot;469789802&quot;:&quot;none&quot;,&quot;469789806&quot;:&quot;none&quot;,&quot;469789810&quot;:&quot;none&quot;,&quot;469789814&quot;:&quot;none&quot;}\">\u00a0<\/span><\/p><p data-ccp-border-bottom=\"0px none #000000\" data-ccp-padding-bottom=\"0px\" data-ccp-border-between=\"0px none #000000\" data-ccp-padding-between=\"0px\"><span data-contrast=\"none\">La tecnolog\u00eda de producci\u00f3n y las fases de control en l\u00ednea permiten comercializar productos con un nivel de calidad constante.<\/span><span data-contrast=\"none\"> A petici\u00f3n expresa del cliente, el sistema FastEnerGrip puede realizarse utilizando membranas de PVC espec\u00edficas; FPO\/TPO, EPDM, BPP\/BPE.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:480,&quot;335572071&quot;:0,&quot;335572072&quot;:0,&quot;335572073&quot;:4278190080,&quot;335572075&quot;:0,&quot;335572076&quot;:0,&quot;335572077&quot;:4278190080,&quot;335572079&quot;:0,&quot;335572080&quot;:0,&quot;335572081&quot;:4278190080,&quot;335572083&quot;:0,&quot;335572084&quot;:0,&quot;335572085&quot;:4278190080,&quot;335572087&quot;:0,&quot;335572088&quot;:0,&quot;335572089&quot;:4278190080,&quot;469789798&quot;:&quot;none&quot;,&quot;469789802&quot;:&quot;none&quot;,&quot;469789806&quot;:&quot;none&quot;,&quot;469789810&quot;:&quot;none&quot;,&quot;469789814&quot;:&quot;none&quot;}\">\u00a0<\/span><\/p><p data-ccp-border-bottom=\"0px none #000000\" data-ccp-padding-bottom=\"0px\" data-ccp-border-between=\"0px none #000000\" data-ccp-padding-between=\"0px\"><span data-contrast=\"none\">A pesar de su joven constituci\u00f3n<\/span><span data-contrast=\"none\"> de la sociedad<\/span><span data-contrast=\"none\">el proyecto <\/span><span data-contrast=\"none\">FastEnerGrip<\/span><span data-contrast=\"none\"> cuenta con un historial de m\u00e1s de 10 a\u00f1os de pruebas en diversas obras con diferentes condiciones ambientales. Esto ha dado como resultado<\/span><span data-contrast=\"none\"> cobertura de seguro a todo riesgo, lo que da fe de la validez de la soluci\u00f3n.<\/span><span data-contrast=\"none\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:480,&quot;335572071&quot;:0,&quot;335572072&quot;:0,&quot;335572073&quot;:4278190080,&quot;335572075&quot;:0,&quot;335572076&quot;:0,&quot;335572077&quot;:4278190080,&quot;335572079&quot;:0,&quot;335572080&quot;:0,&quot;335572081&quot;:4278190080,&quot;335572083&quot;:0,&quot;335572084&quot;:0,&quot;335572085&quot;:4278190080,&quot;335572087&quot;:0,&quot;335572088&quot;:0,&quot;335572089&quot;:4278190080,&quot;469789798&quot;:&quot;none&quot;,&quot;469789802&quot;:&quot;none&quot;,&quot;469789806&quot;:&quot;none&quot;,&quot;469789810&quot;:&quot;none&quot;,&quot;469789814&quot;:&quot;none&quot;}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f38eed3 elementor-widget elementor-widget-n-accordion\" data-id=\"f38eed3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Acorde\u00f3n. Abra los enlaces con Intro o Espacio, ci\u00e9rrelos con Escape y navegue con las teclas de flecha.\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2550\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2550\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> PR\u00d3LOGO <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2550\" class=\"elementor-element elementor-element-b3e339b e-con-full e-flex e-con e-child\" data-id=\"b3e339b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f372f77 elementor-widget elementor-widget-text-editor\" data-id=\"f372f77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La fijaci\u00f3n de superestructuras en cubiertas de edificios representa un reto importante tanto en la construcci\u00f3n civil como en la industrial.<br \/>El proyectista se enfrenta a las siguientes cuestiones, a la vista de que est\u00e1 obligado a cumplir la Orden Ministerial de 17 de enero de 2018 - actualizaci\u00f3n de las Normas T\u00e9cnicas de la Edificaci\u00f3n Cap\u00edtulo 7.2.4:<\/p><ol><li>garantizar una fijaci\u00f3n s\u00f3lida y segura que pueda soportar todas las tensiones que los agentes atmosf\u00e9ricos a trav\u00e9s de la superestructura ejercen directamente sobre los elementos de fijaci\u00f3n en t\u00e9rminos de resistencia a la tracci\u00f3n y al cizallamiento;<\/li><li>garantizar una perfecta estanqueidad mediante el sistema de fijaci\u00f3n elegido.<\/li><\/ol><p>Proroof Ltd. se esfuerza constantemente, mediante estudios y aplicaciones, por ofrecer el sistema FastEnerGrip al dise\u00f1ador, al aplicador y al cliente. <br \/>El sistema FastEnerGrip resuelve todos los problemas necesarios para una fijaci\u00f3n segura, duradera e impermeable.<\/p><p>Gracias al sistema patentado FSTENERGRIP, Proroof puede ofrecer las siguientes ventajas :<\/p><ol><li>Resistencia a la tracci\u00f3n de 3,5 kN a 54 kN;<\/li><li>Resistencia al cizallamiento de 6,9 kN a 35 kN;<\/li><li>Estanqueidad absoluta del sistema de fijaci\u00f3n;<\/li><li>Adecuado para su uso en superficies con una inclinaci\u00f3n de m\u00e1s de 45\u00b0.<\/li><li>Caracter\u00edsticas constantes en el tiempo y reproducibles.<\/li><\/ol><p>\u00a0<\/p><p>El sistema FastEnerGrip se monta \u00edntegramente en f\u00e1brica en condiciones ambientales constantes y en ausencia de contaminantes<br \/>tales como: polvo agua etc. elementos que pueden afectar al rendimiento mec\u00e1nico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2551\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2551\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> FASTENERGRIP <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2551\" class=\"elementor-element elementor-element-5bd1d87 e-con-full e-flex e-con e-child\" data-id=\"5bd1d87\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8ed94b9 elementor-widget elementor-widget-text-editor\" data-id=\"8ed94b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>FastEnerGrip es un sistema dise\u00f1ado para asegurar la fijaci\u00f3n de equipos tales como sistemas fotovoltaicos, sistemas solares t\u00e9rmicos, parapetos, l\u00edneas de vida, sistemas de tratamiento de aire y otros equipos que generalmente se colocan en cubiertas impermeabilizadas con cubiertas visibles tales como: FPO \/ TPO, PVC, EPDM, membranas bituminosas, impermeabilizaci\u00f3n l\u00edquida, etc.<br \/>La tecnolog\u00eda especial de montaje por doble inducci\u00f3n simult\u00e1nea de FastEnerGrip garantiza una conexi\u00f3n segura <br \/>excelentes prestaciones mec\u00e1nicas directamente a la estructura del tejado sin elementos de fijaci\u00f3n pasantes. <br \/>Una vez instalado y soldado por termofusi\u00f3n, si se instala correctamente FastEnerGrip elimina el movimiento de cremallera y garantiza una estanqueidad sin concesiones. <br \/>El dise\u00f1o de FastEnerGrip fue concebido para facilitar su instalaci\u00f3n a los profesionales.<\/p><p>Cada lote de FastEnerGrip\u00ae se somete a controles sistem\u00e1ticos que se llevan a cabo tanto en laboratorios propios como en instalaciones externas certificadas.<br \/>Un sofisticado sistema de control termogr\u00e1fico, montado en l\u00ednea, permite detectar inmediatamente cualquier defecto.<br \/>Adem\u00e1s, nuestros laboratorios est\u00e1n equipados para realizar ensayos de resistencia al cizallamiento y a la tracci\u00f3n.<br \/>Estas pruebas tambi\u00e9n pueden realizarse, a petici\u00f3n expresa por escrito del cliente, en laboratorios externos certificados o in situ. Adem\u00e1s de comprobar sistem\u00e1ticamente el producto acabado, Proroof srl prueba constantemente las membranas utilizadas en la producci\u00f3n del sistema FastEnerGrip\u00ae.<br \/>A petici\u00f3n del cliente, tambi\u00e9n se realizan pruebas en membranas previamente instaladas sujetas a la colocaci\u00f3n del sistema FastEnerGrip<\/p><p>El sistema FastEnerGrip consta de:<\/p><ul><li>Disco de 90 m, de aluminio Anticorodal, de 10 mm de espesor, que proporciona un soporte perfecto para las estructuras y\/o armazones sobre los que se instalar\u00e1n las superestructuras.<\/li><li>Perno de sujeci\u00f3n M10x35 A2, se pueden suministrar pernos M12 x 35 A2 a petici\u00f3n del cliente.<\/li><li>FastEnerGrip puede fabricarse con todos los tipos de membranas impermeabilizantes del mercado y son totalmente compatibles con los sistemas de colocaci\u00f3n mediante fijaci\u00f3n mec\u00e1nica, pegado o lastrado. <br \/>- El sistema FastEnerGrip puede utilizarse en todo tipo de sustratos y espesores:<br \/>Metal &gt; de 0,4 mm<br \/>Madera &gt; 10 mm<br \/>Hormig\u00f3n &gt; 40 mm<br \/>Losas de cemento &gt; 10 mm<\/li><\/ul><p>\u00a0<\/p><p>La posibilidad de implementar el sistema FastEnerGrip con cualquier membrana impermeabilizante del mercado garantiza la compatibilidad de la 100% con el sistema de impermeabilizaci\u00f3n instalado y\/o a instalar.<br \/>El sistema FastEnerGrip no requiere ninguna preparaci\u00f3n previa a la aplicaci\u00f3n de la membrana impermeabilizante para su colocaci\u00f3n en la estructura, lo que ayuda a ahorrar tiempo y mano de obra con la posibilidad de cambiar la disposici\u00f3n de colocaci\u00f3n hasta el \u00faltimo momento. <br \/>La correcta instalaci\u00f3n de FastEnerGrip asegura una fijaci\u00f3n segura y potente del equipo al tejado, garantizando una estanqueidad total. <\/p><ul><li>Sencillo proceso de instalaci\u00f3n que ahorra tiempo y mano de obra. <\/li><li>100% compatible con todas las membranas impermeables preparadas para la termofusi\u00f3n por inducci\u00f3n. <\/li><li>Ayuda a proteger la cubierta del tejado de da\u00f1os debidos al movimiento del bastidor causado por el balasto y de filtraciones debidas al uso de selladores para a trav\u00e9s de fijaciones mec\u00e1nicas.<\/li><li>Gran brida de 250 mm de di\u00e1metro para soldar a la membrana impermeabilizante principal.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2552\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2552\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> VERSIONES <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2552\" class=\"elementor-element elementor-element-82e5133 e-con-full e-flex e-con e-child\" data-id=\"82e5133\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ffdd9d8 elementor-widget elementor-widget-text-editor\" data-id=\"ffdd9d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El sistema FastEnerGrip est\u00e1 disponible en las siguientes versiones:<\/p><p><strong>FastEnerGrip PV- base<\/strong><br \/>Para uso cuando las prestaciones mec\u00e1nicas requeridas no superen los 3,0 kN de tracci\u00f3n y los 2,0 kN de cizalladura.<\/p><p><strong>FastEnerGrip PV- P- 0,6<\/strong><br \/>Para utilizar cuando las prestaciones mec\u00e1nicas requeridas no superen los 9,5 kN de tracci\u00f3n y los 6,8 kN de cizalladura.<\/p><p><strong>FastEnerGrip PV- HP<\/strong><br \/>Debe utilizarse cuando las prestaciones mec\u00e1nicas requeridas no superen 28,0 kN de tracci\u00f3n y 20,0 kN de cizalladura.<\/p><p><strong>FastEnerGrip HP-LV<\/strong><br \/>Para utilizar cuando las prestaciones mec\u00e1nicas requeridas no superen 44,0 kN de tracci\u00f3n y 32,0 kN de cizalladura (Sistema utilizado para posicionar componentes de la L\u00ednea de Vida.<\/p><p>El sistema se realiza con pernos M16x 30\/40\/50\/60\/70\/100<br \/>Una amplia gama de accesorios permite colocar los paneles fotovoltaicos desde coplanarios al tejado hasta inclinaciones verticales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b334c9 elementor-cta--skin-classic elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"9b334c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tDescargar el PDF con todos los detalles\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/12\/FastEnerGrip-PV-10.1-24-IT-EN-D-SP-FR.pdf\" target=\"_blank\">\n\t\t\t\t\t\tDescargar\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b54e2e8 e-grid e-con-boxed e-con e-parent\" data-id=\"b54e2e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a4604e4 elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget__width-initial e-transform elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"a4604e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.proroofsrl.com\/es\/fastenergrip-easy\/\" tabindex=\"-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/Easy-.webp\" class=\"elementor-animation-grow attachment-medium_large size-medium_large wp-image-355\" alt=\"\" srcset=\"https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/Easy-.webp 1024w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/Easy--300x300.webp 300w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/Easy--150x150.webp 150w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.proroofsrl.com\/es\/fastenergrip-easy\/\">FastEnerGrip EASY<\/a><\/h4><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fe7946 elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2fe7946\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.proroofsrl.com\/es\/fastenergrip-pv\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/FastEnerGrip-6-768x768.png\" class=\"elementor-animation-grow attachment-medium_large size-medium_large wp-image-352\" alt=\"\" srcset=\"https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/FastEnerGrip-6-768x768.png 768w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/FastEnerGrip-6-300x300.png 300w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/FastEnerGrip-6-150x150.png 150w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/FastEnerGrip-6-12x12.png 12w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/FastEnerGrip-6.png 1024w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.proroofsrl.com\/es\/fastenergrip-pv\/\">FastEnerGrip PV<\/a><\/h4><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81cfe75 elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"81cfe75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.proroofsrl.com\/es\/fastenergrip-pv-pro\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/Schermata-2022-12-06-alle-19.17.31-768x768.jpg\" class=\"elementor-animation-grow attachment-medium_large size-medium_large wp-image-354\" alt=\"\" srcset=\"https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/Schermata-2022-12-06-alle-19.17.31-768x768.jpg 768w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/Schermata-2022-12-06-alle-19.17.31-300x300.jpg 300w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/Schermata-2022-12-06-alle-19.17.31-150x150.jpg 150w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/Schermata-2022-12-06-alle-19.17.31-12x12.jpg 12w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/Schermata-2022-12-06-alle-19.17.31.jpg 1024w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.proroofsrl.com\/es\/fastenergrip-pv-pro\/\">FastEnerGrip PV PRO<\/a><\/h4><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-099cd46 elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"099cd46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.proroofsrl.com\/es\/fastenergrip-gf\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"472\" src=\"https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/Soggetto-11-768x472.png\" class=\"elementor-animation-grow attachment-medium_large size-medium_large wp-image-356\" alt=\"\" srcset=\"https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/Soggetto-11-768x472.png 768w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/Soggetto-11-300x184.png 300w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/Soggetto-11-1024x629.png 1024w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/Soggetto-11-1536x943.png 1536w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/Soggetto-11-2048x1258.png 2048w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/Soggetto-11-18x12.png 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.proroofsrl.com\/es\/fastenergrip-gf\/\">FastEnerGrip GF<\/a><\/h4><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7142d3 elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b7142d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.proroofsrl.com\/es\/fastenergrip-pv-lt\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"489\" src=\"https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/FastEnerGrip-PV-LT-fronte--768x489.png\" class=\"elementor-animation-grow attachment-medium_large size-medium_large wp-image-359\" alt=\"\" srcset=\"https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/FastEnerGrip-PV-LT-fronte--768x489.png 768w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/FastEnerGrip-PV-LT-fronte--300x191.png 300w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/FastEnerGrip-PV-LT-fronte--1024x651.png 1024w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/FastEnerGrip-PV-LT-fronte--1536x977.png 1536w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/FastEnerGrip-PV-LT-fronte--2048x1303.png 2048w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/FastEnerGrip-PV-LT-fronte--18x12.png 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.proroofsrl.com\/es\/fastenergrip-pv-lt\/\">FastEnerGrip PV LT<\/a><\/h4><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f983e0b elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f983e0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.proroofsrl.com\/es\/fastenergrip-lv\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1027\" src=\"https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/a3080bbf-4641-4768-8371-a185c6c2b524-768x1027.jpg\" class=\"elementor-animation-grow attachment-medium_large size-medium_large wp-image-357\" alt=\"\" srcset=\"https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/a3080bbf-4641-4768-8371-a185c6c2b524-768x1027.jpg 768w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/a3080bbf-4641-4768-8371-a185c6c2b524-224x300.jpg 224w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/a3080bbf-4641-4768-8371-a185c6c2b524-765x1024.jpg 765w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/a3080bbf-4641-4768-8371-a185c6c2b524-1148x1536.jpg 1148w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/a3080bbf-4641-4768-8371-a185c6c2b524-9x12.jpg 9w, https:\/\/www.proroofsrl.com\/wp-content\/uploads\/2024\/11\/a3080bbf-4641-4768-8371-a185c6c2b524.jpg 1196w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.proroofsrl.com\/es\/fastenergrip-lv\/\">FastEnerGrip LV<\/a><\/h4><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Sistemi di fissaggio a tenuta stagna L\u2019installazione di sovrastrutture quali, ad esempio, pannelli fotovoltaici, solare termico, tubazioni, cavi riscaldanti, parabole etc., hanno sempre destato preoccupazione e posto particolari limiti sia al progettista che all\u2019applicatore.\u00a0 L\u2019esperienza accumulata in oltre 30 anni di attivit\u00e0 nel comparto delle impermeabilizzazioni ha permesso lo sviluppo di una serie di prodotti, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_angie_page":false,"footnotes":""},"class_list":["post-77","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.proroofsrl.com\/es\/wp-json\/wp\/v2\/pages\/77","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.proroofsrl.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.proroofsrl.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.proroofsrl.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proroofsrl.com\/es\/wp-json\/wp\/v2\/comments?post=77"}],"version-history":[{"count":40,"href":"https:\/\/www.proroofsrl.com\/es\/wp-json\/wp\/v2\/pages\/77\/revisions"}],"predecessor-version":[{"id":684,"href":"https:\/\/www.proroofsrl.com\/es\/wp-json\/wp\/v2\/pages\/77\/revisions\/684"}],"wp:attachment":[{"href":"https:\/\/www.proroofsrl.com\/es\/wp-json\/wp\/v2\/media?parent=77"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}